{"id":6566,"date":"2023-04-25T10:34:32","date_gmt":"2023-04-25T08:34:32","guid":{"rendered":"https:\/\/levillagebalinais.com\/?p=6566"},"modified":"2023-04-25T10:37:35","modified_gmt":"2023-04-25T08:37:35","slug":"seances-de-massages-duo-mai-et-juin-au-village-balinais-paris","status":"publish","type":"post","link":"https:\/\/levillagebalinais.com\/index.php\/2023\/04\/25\/seances-de-massages-duo-mai-et-juin-au-village-balinais-paris\/","title":{"rendered":"S\u00e9ances de massages duo Mai et Juin au Village Balinais Paris"},"content":{"rendered":"<p><strong>CALENDRIER SEANCE DE <a href=\"https:\/\/levillagebalinais.com\/index.php\/studio-massage\/massages\/\">MASSAGES DUO<\/a><\/strong><\/p>\n<p>Profitez bien de ces s\u00e9ances avant mon d\u00e9part \u00e0 Bali!<\/p>\n<p><strong><em>MAI :<\/em><\/strong><\/p>\n<li><em> Samedi 20 Mai 10h-18h<\/em><\/li>\n<p><strong><em>JUIN : <\/em><\/strong><\/p>\n<li><em>Samedi 3 Juin 10h-18h<\/em><\/li>\n<li><em>Samedi 17 Juin 10h-18h<\/em><\/li>\n<p>Tarifs des s\u00e9ances duo  au <a href=\"https:\/\/levillagebalinais.com\/index.php\/studio-massage\/presentation\/\">Studio du Village Balinais<\/a>:<\/p>\n<li><em>60mn :150\u20ac<\/em><\/li>\n<li><em>90mn :210\u20ac<\/em><\/li>\n<p>Le studio confidentiel calme et lumineux est privatis\u00e9. Ruth et H\u00e9l\u00e8ne prennent le temps de vous accueillir et vous guident dans votre s\u00e9ance en s&rsquo;adaptant \u00e0 vos besoins de d\u00e9tente.<\/p>\n<p>Pour prendre RDV, valider la disponibilit\u00e9 du cr\u00e9neau, merci de contacter directement le Village Balinais par t\u00e9l\u00e9phone ou en nous adressant votre demande par le <a href=\"https:\/\/levillagebalinais.com\/index.php\/contact-2\/\">formulaire de contact<\/a>.<br \/>\n<strong>T\u00e9l : 06 50 20 62 33 <\/strong><\/p>\n<p><strong><em>Actualit\u00e9s du Village Balinais :<\/em><\/strong><br \/>\n\t<em><\/p>\n<li>Paru dans le journal professionnel Spa de Beaut\u00e9 Avril 2023, un article du village balinais sur l&rsquo;authenticit\u00e9 des racines et 3 spas test\u00e9s par Ruth Indiathi en 2022 \u00e0 Bali et Java  :<br \/>\n<a href=\"https:\/\/levillagebalinais.com\/index.php\/2023\/04\/16\/jai-teste-les-spas-de-bali-et-java-avril-2023\/\">J&rsquo;ai test\u00e9 des spas en Indon\u00e9sie : l&rsquo;authenticit\u00e9 de l&rsquo;h\u00e9ritage | Magazine Spa de Beaut\u00e9<\/a><\/li>\n<p><\/em><\/p>\n<li>A d\u00e9couvrir durant notre formation,  notre s\u00e9lection exclusive  d&rsquo;huiles  issue de la pharmacop\u00e9e indon\u00e9sienne, chauffante, myorelaxante, et  notre  nouvelle gamme huile  spa bio \u00e9cobert textur\u00e9e pour le massage spa aux ar\u00f4mes subtiles et frais.<\/li>\n<li><em><a href=\"https:\/\/levillagebalinais.com\/index.php\/2023\/04\/01\/formation-massages-balinais-en-immersion-a-bali-ete-2023-dernieres-places-avant-cloture-des-inscriptions\/\">Derni\u00e8re place pour l&rsquo;inscription \u00e0 la formation en immersion \u00e0 Bali \u00e9t\u00e9 2023 : Formation massages balinais en immersion \u00e0 Bali \u00e9t\u00e9 2023 : Derni\u00e8res places avant cl\u00f4ture des inscriptions \u2013 Le Village Balinais<\/a><\/em><\/li>\n","protected":false},"excerpt":{"rendered":"<p>CALENDRIER SEANCE DE MASSAGES DUO Profitez bien de ces s\u00e9ances avant mon d\u00e9part \u00e0 Bali! MAI : Samedi 20 Mai 10h-18h JUIN : Samedi 3 Juin 10h-18h Samedi 17 Juin 10h-18h Tarifs des s\u00e9ances duo au Studio du Village Balinais: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6175,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/levillagebalinais.com\/index.php\/wp-json\/wp\/v2\/posts\/6566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/levillagebalinais.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/levillagebalinais.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/levillagebalinais.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/levillagebalinais.com\/index.php\/wp-json\/wp\/v2\/comments?post=6566"}],"version-history":[{"count":3,"href":"https:\/\/levillagebalinais.com\/index.php\/wp-json\/wp\/v2\/posts\/6566\/revisions"}],"predecessor-version":[{"id":6570,"href":"https:\/\/levillagebalinais.com\/index.php\/wp-json\/wp\/v2\/posts\/6566\/revisions\/6570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/levillagebalinais.com\/index.php\/wp-json\/wp\/v2\/media\/6175"}],"wp:attachment":[{"href":"https:\/\/levillagebalinais.com\/index.php\/wp-json\/wp\/v2\/media?parent=6566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/levillagebalinais.com\/index.php\/wp-json\/wp\/v2\/categories?post=6566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/levillagebalinais.com\/index.php\/wp-json\/wp\/v2\/tags?post=6566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}